{"id":1584,"date":"2018-10-31T13:04:04","date_gmt":"2018-10-31T13:04:04","guid":{"rendered":"https:\/\/www.brideamedical.com\/contact\/where-to-buy\/"},"modified":"2024-10-15T23:01:56","modified_gmt":"2024-10-15T21:01:56","slug":"bezugsquellen","status":"publish","type":"page","link":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/","title":{"rendered":"Bezugsquellen"},"content":{"rendered":"<p class=\"h1\">Kundendienst<\/p>\n<p>Wonach suchen Sie?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kundendienst Wonach suchen Sie?<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1582,"menu_order":76,"comment_status":"closed","ping_status":"closed","template":"views\/template-customer-service.blade.php","meta":{"_acf_changed":false,"content-type":"","_improvement_type_select":"improve_an_existing","_thumb_yes_seoaic":false,"_frame_yes_seoaic":false,"seoaic_generate_description":"","seoaic_improve_instructions_prompt":"","seoaic_rollback_content_improvement":"","seoaic_idea_thumbnail_generator":"","thumbnail_generated":false,"thumbnail_generate_prompt":"","seoaic_article_description":"","footnotes":""},"class_list":["post-1584","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bezugsquellen the specula - Bridea Medical<\/title>\n<meta name=\"description\" content=\"Buy direct online from our online store.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bezugsquellen the specula - Bridea Medical\" \/>\n<meta property=\"og:description\" content=\"Buy direct online from our online store.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Bridea Medical\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T21:01:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BrideaMedical\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/bezugsquellen\\\/\",\"url\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/bezugsquellen\\\/\",\"name\":\"Bezugsquellen the specula - Bridea Medical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#website\"},\"datePublished\":\"2018-10-31T13:04:04+00:00\",\"dateModified\":\"2024-10-15T21:01:56+00:00\",\"description\":\"Buy direct online from our online store.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/bezugsquellen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/bezugsquellen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/bezugsquellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakt\",\"item\":\"https:\\\/\\\/www.brideamedical.com\\\/de\\\/kontakt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bezugsquellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#website\",\"url\":\"https:\\\/\\\/www.brideamedical.com\\\/\",\"name\":\"Bridea Medical\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.brideamedical.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#organization\",\"name\":\"Bridea Medical B.V.\",\"url\":\"https:\\\/\\\/www.brideamedical.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.brideamedical.com\\\/app\\\/uploads\\\/2018\\\/10\\\/brideamedical_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.brideamedical.com\\\/app\\\/uploads\\\/2018\\\/10\\\/brideamedical_logo.png\",\"width\":300,\"height\":101,\"caption\":\"Bridea Medical B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.brideamedical.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/BrideaMedical\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/bridea-medical\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bezugsquellen the specula - Bridea Medical","description":"Buy direct online from our online store.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/","og_locale":"de_DE","og_type":"article","og_title":"Bezugsquellen the specula - Bridea Medical","og_description":"Buy direct online from our online store.","og_url":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/","og_site_name":"Bridea Medical","article_modified_time":"2024-10-15T21:01:56+00:00","twitter_card":"summary_large_image","twitter_site":"@BrideaMedical","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/","url":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/","name":"Bezugsquellen the specula - Bridea Medical","isPartOf":{"@id":"https:\/\/www.brideamedical.com\/#website"},"datePublished":"2018-10-31T13:04:04+00:00","dateModified":"2024-10-15T21:01:56+00:00","description":"Buy direct online from our online store.","breadcrumb":{"@id":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.brideamedical.com\/de\/kontakt\/bezugsquellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.brideamedical.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kontakt","item":"https:\/\/www.brideamedical.com\/de\/kontakt\/"},{"@type":"ListItem","position":3,"name":"Bezugsquellen"}]},{"@type":"WebSite","@id":"https:\/\/www.brideamedical.com\/#website","url":"https:\/\/www.brideamedical.com\/","name":"Bridea Medical","description":"","publisher":{"@id":"https:\/\/www.brideamedical.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brideamedical.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.brideamedical.com\/#organization","name":"Bridea Medical B.V.","url":"https:\/\/www.brideamedical.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.brideamedical.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.brideamedical.com\/app\/uploads\/2018\/10\/brideamedical_logo.png","contentUrl":"https:\/\/www.brideamedical.com\/app\/uploads\/2018\/10\/brideamedical_logo.png","width":300,"height":101,"caption":"Bridea Medical B.V."},"image":{"@id":"https:\/\/www.brideamedical.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/BrideaMedical","https:\/\/nl.linkedin.com\/company\/bridea-medical"]}]}},"_links":{"self":[{"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/pages\/1584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/comments?post=1584"}],"version-history":[{"count":40,"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/pages\/1584\/revisions"}],"predecessor-version":[{"id":5402,"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/pages\/1584\/revisions\/5402"}],"up":[{"embeddable":true,"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/pages\/1582"}],"wp:attachment":[{"href":"https:\/\/www.brideamedical.com\/de\/wp-json\/wp\/v2\/media?parent=1584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}